{"id":46,"date":"2022-09-26T22:57:00","date_gmt":"2022-09-26T22:57:00","guid":{"rendered":"http:\/\/box5378.temp.domains\/~trashrec\/zekemason\/?p=46"},"modified":"2022-12-28T20:44:43","modified_gmt":"2022-12-28T20:44:43","slug":"album-last","status":"publish","type":"post","link":"https:\/\/trashrecords.org\/zekemason\/album-last\/","title":{"rendered":"Album: Last"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>Last<\/em> follows up on 2021\u2019s <em>Whilst it Waits<\/em> with 9 new instrumental compositions.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/trashrecords.org\/MusicDownloads\/Zeke Mason\/Z11 last\/01 Bells.m4a\">01 Bells<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/trashrecords.org\/MusicDownloads\/Zeke Mason\/Z11 last\/02 Fleet.m4a\">02 Fleet<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/trashrecords.org\/MusicDownloads\/Zeke Mason\/Z11 last\/03 Brute.m4a\">03 Brute<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/trashrecords.org\/MusicDownloads\/Zeke Mason\/Z11 last\/04 Place.m4a\">04 Place<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/trashrecords.org\/MusicDownloads\/Zeke Mason\/Z11 last\/05 Call.m4a\">05 Call<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/trashrecords.org\/MusicDownloads\/Zeke Mason\/Z11 last\/06 Response.m4a\">06 Response<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/trashrecords.org\/MusicDownloads\/Zeke Mason\/Z11 last\/07 Locality.m4a\">07 Locality<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/trashrecords.org\/MusicDownloads\/Zeke Mason\/Z11 last\/08 We Decay.m4a\">08 We Decay<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/trashrecords.org\/MusicDownloads\/Zeke Mason\/Z11 last\/09 Last.m4a\">09 Last<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">And, you can stream it on youtube:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Zeke Mason: Last (Full Album 2022 Instrumental post-rock)\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/1rU24EWQcT8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Last follows up on 2021\u2019s Whilst it Waits with 9 new instrumental compositions. 01 Bells 02 Fleet 03 Brute 04 Place 05 Call 06 Response 07 Locality 08 We Decay 09 Last And, you can stream it on youtube:<\/p>\n","protected":false},"author":1,"featured_media":48,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[4],"class_list":["post-46","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-albums","tag-music","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Album: Last - Zeke Mason<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trashrecords.org\/zekemason\/album-last\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Album: Last - Zeke Mason\" \/>\n<meta property=\"og:description\" content=\"Last follows up on 2021\u2019s Whilst it Waits with 9 new instrumental compositions. 01 Bells 02 Fleet 03 Brute 04 Place 05 Call 06 Response 07 Locality 08 We Decay 09 Last And, you can stream it on youtube:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trashrecords.org\/zekemason\/album-last\/\" \/>\n<meta property=\"og:site_name\" content=\"Zeke Mason\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-26T22:57:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-28T20:44:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trashrecords.org\/zekemason\/wp-content\/uploads\/2022\/12\/Z10-Last.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"855\" \/>\n\t<meta property=\"og:image:height\" content=\"690\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"masontattersall\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"masontattersall\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/trashrecords.org\\\/zekemason\\\/album-last\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trashrecords.org\\\/zekemason\\\/album-last\\\/\"},\"author\":{\"name\":\"masontattersall\",\"@id\":\"http:\\\/\\\/box5378.temp.domains\\\/~trashrec\\\/zekemason\\\/#\\\/schema\\\/person\\\/2fd8a63fba64c3a30da2d86d21bb079b\"},\"headline\":\"Album: Last\",\"datePublished\":\"2022-09-26T22:57:00+00:00\",\"dateModified\":\"2022-12-28T20:44:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/trashrecords.org\\\/zekemason\\\/album-last\\\/\"},\"wordCount\":36,\"image\":{\"@id\":\"https:\\\/\\\/trashrecords.org\\\/zekemason\\\/album-last\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/trashrecords.org\\\/zekemason\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Z10-Last.jpg?fit=855%2C690&ssl=1\",\"keywords\":[\"music\"],\"articleSection\":[\"Albums\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/trashrecords.org\\\/zekemason\\\/album-last\\\/\",\"url\":\"https:\\\/\\\/trashrecords.org\\\/zekemason\\\/album-last\\\/\",\"name\":\"Album: Last - Zeke Mason\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/box5378.temp.domains\\\/~trashrec\\\/zekemason\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/trashrecords.org\\\/zekemason\\\/album-last\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/trashrecords.org\\\/zekemason\\\/album-last\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/trashrecords.org\\\/zekemason\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Z10-Last.jpg?fit=855%2C690&ssl=1\",\"datePublished\":\"2022-09-26T22:57:00+00:00\",\"dateModified\":\"2022-12-28T20:44:43+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/box5378.temp.domains\\\/~trashrec\\\/zekemason\\\/#\\\/schema\\\/person\\\/2fd8a63fba64c3a30da2d86d21bb079b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/trashrecords.org\\\/zekemason\\\/album-last\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/trashrecords.org\\\/zekemason\\\/album-last\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/trashrecords.org\\\/zekemason\\\/album-last\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/trashrecords.org\\\/zekemason\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Z10-Last.jpg?fit=855%2C690&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/trashrecords.org\\\/zekemason\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Z10-Last.jpg?fit=855%2C690&ssl=1\",\"width\":855,\"height\":690},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/trashrecords.org\\\/zekemason\\\/album-last\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/box5378.temp.domains\\\/~trashrec\\\/zekemason\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Album: Last\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/box5378.temp.domains\\\/~trashrec\\\/zekemason\\\/#website\",\"url\":\"http:\\\/\\\/box5378.temp.domains\\\/~trashrec\\\/zekemason\\\/\",\"name\":\"Zeke Mason\",\"description\":\"Prepare to be Disappointed\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/box5378.temp.domains\\\/~trashrec\\\/zekemason\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/box5378.temp.domains\\\/~trashrec\\\/zekemason\\\/#\\\/schema\\\/person\\\/2fd8a63fba64c3a30da2d86d21bb079b\",\"name\":\"masontattersall\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b1c03673320a2fcd210237c4f845e63e2843d4d154d8fa84adf4de9d5bfff0d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b1c03673320a2fcd210237c4f845e63e2843d4d154d8fa84adf4de9d5bfff0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b1c03673320a2fcd210237c4f845e63e2843d4d154d8fa84adf4de9d5bfff0d?s=96&d=mm&r=g\",\"caption\":\"masontattersall\"},\"url\":\"https:\\\/\\\/trashrecords.org\\\/zekemason\\\/author\\\/masontattersall\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Album: Last - Zeke Mason","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trashrecords.org\/zekemason\/album-last\/","og_locale":"en_US","og_type":"article","og_title":"Album: Last - Zeke Mason","og_description":"Last follows up on 2021\u2019s Whilst it Waits with 9 new instrumental compositions. 01 Bells 02 Fleet 03 Brute 04 Place 05 Call 06 Response 07 Locality 08 We Decay 09 Last And, you can stream it on youtube:","og_url":"https:\/\/trashrecords.org\/zekemason\/album-last\/","og_site_name":"Zeke Mason","article_published_time":"2022-09-26T22:57:00+00:00","article_modified_time":"2022-12-28T20:44:43+00:00","og_image":[{"width":855,"height":690,"url":"https:\/\/trashrecords.org\/zekemason\/wp-content\/uploads\/2022\/12\/Z10-Last.jpg","type":"image\/jpeg"}],"author":"masontattersall","twitter_card":"summary_large_image","twitter_misc":{"Written by":"masontattersall","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/trashrecords.org\/zekemason\/album-last\/#article","isPartOf":{"@id":"https:\/\/trashrecords.org\/zekemason\/album-last\/"},"author":{"name":"masontattersall","@id":"http:\/\/box5378.temp.domains\/~trashrec\/zekemason\/#\/schema\/person\/2fd8a63fba64c3a30da2d86d21bb079b"},"headline":"Album: Last","datePublished":"2022-09-26T22:57:00+00:00","dateModified":"2022-12-28T20:44:43+00:00","mainEntityOfPage":{"@id":"https:\/\/trashrecords.org\/zekemason\/album-last\/"},"wordCount":36,"image":{"@id":"https:\/\/trashrecords.org\/zekemason\/album-last\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/trashrecords.org\/zekemason\/wp-content\/uploads\/2022\/12\/Z10-Last.jpg?fit=855%2C690&ssl=1","keywords":["music"],"articleSection":["Albums"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/trashrecords.org\/zekemason\/album-last\/","url":"https:\/\/trashrecords.org\/zekemason\/album-last\/","name":"Album: Last - Zeke Mason","isPartOf":{"@id":"http:\/\/box5378.temp.domains\/~trashrec\/zekemason\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trashrecords.org\/zekemason\/album-last\/#primaryimage"},"image":{"@id":"https:\/\/trashrecords.org\/zekemason\/album-last\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/trashrecords.org\/zekemason\/wp-content\/uploads\/2022\/12\/Z10-Last.jpg?fit=855%2C690&ssl=1","datePublished":"2022-09-26T22:57:00+00:00","dateModified":"2022-12-28T20:44:43+00:00","author":{"@id":"http:\/\/box5378.temp.domains\/~trashrec\/zekemason\/#\/schema\/person\/2fd8a63fba64c3a30da2d86d21bb079b"},"breadcrumb":{"@id":"https:\/\/trashrecords.org\/zekemason\/album-last\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trashrecords.org\/zekemason\/album-last\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/trashrecords.org\/zekemason\/album-last\/#primaryimage","url":"https:\/\/i0.wp.com\/trashrecords.org\/zekemason\/wp-content\/uploads\/2022\/12\/Z10-Last.jpg?fit=855%2C690&ssl=1","contentUrl":"https:\/\/i0.wp.com\/trashrecords.org\/zekemason\/wp-content\/uploads\/2022\/12\/Z10-Last.jpg?fit=855%2C690&ssl=1","width":855,"height":690},{"@type":"BreadcrumbList","@id":"https:\/\/trashrecords.org\/zekemason\/album-last\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/box5378.temp.domains\/~trashrec\/zekemason\/"},{"@type":"ListItem","position":2,"name":"Album: Last"}]},{"@type":"WebSite","@id":"http:\/\/box5378.temp.domains\/~trashrec\/zekemason\/#website","url":"http:\/\/box5378.temp.domains\/~trashrec\/zekemason\/","name":"Zeke Mason","description":"Prepare to be Disappointed","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/box5378.temp.domains\/~trashrec\/zekemason\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"http:\/\/box5378.temp.domains\/~trashrec\/zekemason\/#\/schema\/person\/2fd8a63fba64c3a30da2d86d21bb079b","name":"masontattersall","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/7b1c03673320a2fcd210237c4f845e63e2843d4d154d8fa84adf4de9d5bfff0d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7b1c03673320a2fcd210237c4f845e63e2843d4d154d8fa84adf4de9d5bfff0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b1c03673320a2fcd210237c4f845e63e2843d4d154d8fa84adf4de9d5bfff0d?s=96&d=mm&r=g","caption":"masontattersall"},"url":"https:\/\/trashrecords.org\/zekemason\/author\/masontattersall\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/trashrecords.org\/zekemason\/wp-content\/uploads\/2022\/12\/Z10-Last.jpg?fit=855%2C690&ssl=1","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/trashrecords.org\/zekemason\/wp-json\/wp\/v2\/posts\/46","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trashrecords.org\/zekemason\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trashrecords.org\/zekemason\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trashrecords.org\/zekemason\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/trashrecords.org\/zekemason\/wp-json\/wp\/v2\/comments?post=46"}],"version-history":[{"count":3,"href":"https:\/\/trashrecords.org\/zekemason\/wp-json\/wp\/v2\/posts\/46\/revisions"}],"predecessor-version":[{"id":116,"href":"https:\/\/trashrecords.org\/zekemason\/wp-json\/wp\/v2\/posts\/46\/revisions\/116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trashrecords.org\/zekemason\/wp-json\/wp\/v2\/media\/48"}],"wp:attachment":[{"href":"https:\/\/trashrecords.org\/zekemason\/wp-json\/wp\/v2\/media?parent=46"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trashrecords.org\/zekemason\/wp-json\/wp\/v2\/categories?post=46"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trashrecords.org\/zekemason\/wp-json\/wp\/v2\/tags?post=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}